{"id":585,"count":1,"description":"","link":"https:\/\/www.rapisnow.com\/blog\/tag\/%e0%b8%a1%e0%b8%b2%e0%b8%a3%e0%b9%8c%e0%b8%81%e0%b8%b5%e0%b9%89\/","name":"\u0e21\u0e32\u0e23\u0e4c\u0e01\u0e35\u0e49","slug":"%e0%b8%a1%e0%b8%b2%e0%b8%a3%e0%b9%8c%e0%b8%81%e0%b8%b5%e0%b9%89","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0e21\u0e32\u0e23\u0e4c\u0e01\u0e35\u0e49 Archives - RAP IS NOW<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rapisnow.com\/blog\/tag\/\u0e21\u0e32\u0e23\u0e4c\u0e01\u0e35\u0e49\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e21\u0e32\u0e23\u0e4c\u0e01\u0e35\u0e49 Archives - RAP IS NOW\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rapisnow.com\/blog\/tag\/\u0e21\u0e32\u0e23\u0e4c\u0e01\u0e35\u0e49\/\" \/>\n<meta property=\"og:site_name\" content=\"RAP IS NOW\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.rapisnow.com\/blog\/#website\",\"url\":\"https:\/\/www.rapisnow.com\/blog\/\",\"name\":\"RAP IS NOW\",\"description\":\"Thai Hip-hop Music, Educational and Culture\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.rapisnow.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.rapisnow.com\/blog\/tag\/%e0%b8%a1%e0%b8%b2%e0%b8%a3%e0%b9%8c%e0%b8%81%e0%b8%b5%e0%b9%89\/#webpage\",\"url\":\"https:\/\/www.rapisnow.com\/blog\/tag\/%e0%b8%a1%e0%b8%b2%e0%b8%a3%e0%b9%8c%e0%b8%81%e0%b8%b5%e0%b9%89\/\",\"name\":\"\\u0e21\\u0e32\\u0e23\\u0e4c\\u0e01\\u0e35\\u0e49 Archives - RAP IS NOW\",\"isPartOf\":{\"@id\":\"https:\/\/www.rapisnow.com\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.rapisnow.com\/blog\/tag\/%e0%b8%a1%e0%b8%b2%e0%b8%a3%e0%b9%8c%e0%b8%81%e0%b8%b5%e0%b9%89\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.rapisnow.com\/blog\/tag\/%e0%b8%a1%e0%b8%b2%e0%b8%a3%e0%b9%8c%e0%b8%81%e0%b8%b5%e0%b9%89\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.rapisnow.com\/blog\/tag\/%e0%b8%a1%e0%b8%b2%e0%b8%a3%e0%b9%8c%e0%b8%81%e0%b8%b5%e0%b9%89\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.rapisnow.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\\u0e21\\u0e32\\u0e23\\u0e4c\\u0e01\\u0e35\\u0e49\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e21\u0e32\u0e23\u0e4c\u0e01\u0e35\u0e49 Archives - RAP IS NOW","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rapisnow.com\/blog\/tag\/\u0e21\u0e32\u0e23\u0e4c\u0e01\u0e35\u0e49\/","og_locale":"en_US","og_type":"article","og_title":"\u0e21\u0e32\u0e23\u0e4c\u0e01\u0e35\u0e49 Archives - RAP IS NOW","og_url":"https:\/\/www.rapisnow.com\/blog\/tag\/\u0e21\u0e32\u0e23\u0e4c\u0e01\u0e35\u0e49\/","og_site_name":"RAP IS NOW","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.rapisnow.com\/blog\/#website","url":"https:\/\/www.rapisnow.com\/blog\/","name":"RAP IS NOW","description":"Thai Hip-hop Music, Educational and Culture","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rapisnow.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"CollectionPage","@id":"https:\/\/www.rapisnow.com\/blog\/tag\/%e0%b8%a1%e0%b8%b2%e0%b8%a3%e0%b9%8c%e0%b8%81%e0%b8%b5%e0%b9%89\/#webpage","url":"https:\/\/www.rapisnow.com\/blog\/tag\/%e0%b8%a1%e0%b8%b2%e0%b8%a3%e0%b9%8c%e0%b8%81%e0%b8%b5%e0%b9%89\/","name":"\u0e21\u0e32\u0e23\u0e4c\u0e01\u0e35\u0e49 Archives - RAP IS NOW","isPartOf":{"@id":"https:\/\/www.rapisnow.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.rapisnow.com\/blog\/tag\/%e0%b8%a1%e0%b8%b2%e0%b8%a3%e0%b9%8c%e0%b8%81%e0%b8%b5%e0%b9%89\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rapisnow.com\/blog\/tag\/%e0%b8%a1%e0%b8%b2%e0%b8%a3%e0%b9%8c%e0%b8%81%e0%b8%b5%e0%b9%89\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.rapisnow.com\/blog\/tag\/%e0%b8%a1%e0%b8%b2%e0%b8%a3%e0%b9%8c%e0%b8%81%e0%b8%b5%e0%b9%89\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rapisnow.com\/blog\/"},{"@type":"ListItem","position":2,"name":"\u0e21\u0e32\u0e23\u0e4c\u0e01\u0e35\u0e49"}]}]}},"_links":{"self":[{"href":"https:\/\/www.rapisnow.com\/blog\/wp-json\/wp\/v2\/tags\/585"}],"collection":[{"href":"https:\/\/www.rapisnow.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.rapisnow.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.rapisnow.com\/blog\/wp-json\/wp\/v2\/posts?tags=585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}