{"id":319,"date":"2015-06-12T13:53:33","date_gmt":"2015-06-12T06:53:33","guid":{"rendered":"http:\/\/www.rapisnow.com\/blog\/?p=319"},"modified":"2019-10-25T07:44:17","modified_gmt":"2019-10-25T00:44:17","slug":"the-interview-ballistic-ceo-siamhiphop-com","status":"publish","type":"post","link":"https:\/\/www.rapisnow.com\/blog\/the-interview-ballistic-ceo-siamhiphop-com\/","title":{"rendered":"THE INTERVIEW : &#8220;Ballistic&#8221; CEO OF SIAMHIPHOP.COM"},"content":{"rendered":"<p><strong><br \/>\nBallistic \u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e09\u0e32\u0e22\u0e32 &#8220;\u0e40\u0e08\u0e49\u0e32\u0e1e\u0e48\u0e2d\u0e2a\u0e15\u0e23\u0e35\u0e17\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19&#8221; \u0e08\u0e32\u0e01\u0e41\u0e23\u0e47\u0e1e\u0e40\u0e1b\u0e2d\u0e23\u0e4c <\/strong><br \/>\n<strong>\u0e2a\u0e39\u0e48\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e08\u0e4b\u0e07\u0e46 \u0e17\u0e35\u0e48\u0e1c\u0e25\u0e31\u0e01\u0e14\u0e31\u0e19\u0e27\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e15\u0e23\u0e35\u0e17\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e19\u0e27\u0e07\u0e01\u0e32\u0e23\u2028\u0e2e\u0e34\u0e1e\u0e2e\u0e2d\u0e1e<\/strong><\/p>\n<p>\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e22\u0e34\u0e19\u0e14\u0e35\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e40\u0e23\u0e32\u0e44\u0e14\u0e49\u0e21\u0e35\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e21\u0e32\u0e08\u0e31\u0e1a\u0e40\u0e02\u0e48\u0e32\u0e04\u0e38\u0e22\u0e01\u0e31\u0e1a Ballistic<br \/>\n\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e43\u0e19\u0e19\u0e32\u0e21\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 SneakaVilla<br \/>\n\u0e40\u0e1b\u0e47\u0e19 DJ \u0e40\u0e1b\u0e47\u0e19\u0e04\u0e19\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19 Event \u0e15\u0e48\u0e32\u0e07\u0e46 &#8230; \u0e42\u0e2d\u0e48&#8230; \u0e17\u0e35\u0e48\u0e40\u0e2d\u0e48\u0e22\u0e21\u0e32\u0e04\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48 &#8220;\u0e41\u0e04\u0e48&#8221; \u0e0b\u0e30\u0e41\u0e25\u0e49\u0e27\u0e25\u0e48\u0e30&#8230;<\/p>\n<p>\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e40\u0e23\u0e32\u0e21\u0e32\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e49\u0e32\u0e41\u0e1a\u0e1a\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e2a\u0e21\u0e31\u0e22\u0e27\u0e31\u0e22\u0e25\u0e30\u0e2d\u0e48\u0e2d\u0e19\u0e01\u0e31\u0e19\u0e14\u0e35\u0e01\u0e27\u0e48\u0e32&#8230;<\/p>\n<p style=\"text-align: left;\"><strong><a href=\"http:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball1.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-322\" src=\"http:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball1-600x600.jpg\" alt=\"ball1\" width=\"600\" height=\"600\" srcset=\"https:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball1-600x600.jpg 600w, https:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball1-300x300.jpg 300w, https:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball1-305x305.jpg 305w, https:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball1.jpg 640w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/strong><\/p>\n<p><strong>Q : \u0e1a\u0e2d\u0e25\u0e44\u0e14\u0e49\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e27\u0e07\u0e01\u0e32\u0e23 Hiphop \u0e44\u0e14\u0e49\u0e44\u0e07\u0e2e\u0e30?<\/strong><\/p>\n<p>A : \u0e40\u0e23\u0e34\u0e48\u0e21\u0e08\u0e32\u0e01\u0e15\u0e2d\u0e19\u0e2d\u0e32\u0e22\u0e38 15 \u0e2d\u0e22\u0e32\u0e01\u0e40\u0e25\u0e48\u0e19 Skateboard \u0e01\u0e47\u0e40\u0e23\u0e34\u0e48\u0e21\u0e44\u0e1b\u0e2b\u0e32\u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32\u0e40\u0e25\u0e48\u0e19<br \/>\n\u0e1d\u0e36\u0e01\u0e40\u0e25\u0e48\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e14\u0e39\u0e15\u0e32\u0e21\u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d \u0e44\u0e21\u0e48\u0e23\u0e39\u0e49\u0e27\u0e48\u0e32\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e17\u0e22\u0e32\u0e04\u0e19\u0e40\u0e04\u0e49\u0e32\u0e40\u0e25\u0e48\u0e19\u0e17\u0e35\u0e48\u0e44\u0e2b\u0e19\u0e01\u0e31\u0e19<br \/>\n\u0e1e\u0e2d\u0e23\u0e39\u0e49\u0e41\u0e25\u0e49\u0e27 \u0e01\u0e47\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e01\u0e25\u0e49\u0e32\u0e44\u0e1b\u0e40\u0e25\u0e48\u0e19\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e49\u0e32 \u0e08\u0e19\u0e27\u0e31\u0e19\u0e19\u0e36\u0e07\u0e01\u0e47\u0e44\u0e14\u0e49\u0e40\u0e08\u0e2d\u0e04\u0e19\u0e43\u0e19\u0e0b\u0e2d\u0e22\u0e1a\u0e49\u0e32\u0e19<br \/>\n\u0e17\u0e35\u0e48\u0e40\u0e25\u0e48\u0e19 Skateboard \u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48\u0e0b\u0e2d\u0e22 6 (\u0e1e\u0e31\u0e17\u0e22\u0e32) \u0e01\u0e47\u0e40\u0e25\u0e22\u0e21\u0e35\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e40\u0e02\u0e49\u0e32\u0e01\u0e25\u0e38\u0e48\u0e21<br \/>\n\u0e04\u0e25\u0e38\u0e01\u0e04\u0e25\u0e35\u0e01\u0e31\u0e1a\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21 Skateboard \u0e01\u0e47\u0e08\u0e30\u0e21\u0e35\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e1f\u0e31\u0e07\u0e40\u0e1e\u0e25\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e19\u0e2d\u0e01\u0e17\u0e38\u0e01\u0e41\u0e19\u0e27<br \/>\n\u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30 Hardcore \u0e44\u0e1b\u0e22\u0e31\u0e19 Hiphop \u0e41\u0e15\u0e48\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e15\u0e2d\u0e19\u0e19\u0e31\u0e49\u0e19\u0e40\u0e23\u0e32\u0e2d\u0e34\u0e19<br \/>\n\u0e01\u0e31\u0e1a Hiphop \u0e21\u0e32\u0e01\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14 \u0e40\u0e04\u0e22\u0e44\u0e14\u0e49\u0e14\u0e39 vdo 411 \u0e41\u0e25\u0e30\u0e43\u0e19\u0e21\u0e49\u0e27\u0e19\u0e19\u0e31\u0e49\u0e19<br \/>\n\u0e21\u0e35\u0e40\u0e1e\u0e25\u0e07 My Name is &#8211; Eminem \u0e41\u0e25\u0e30\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e27\u0e48\u0e32\u0e0a\u0e2d\u0e1a\u0e21\u0e32\u0e01<br \/>\n\u0e41\u0e25\u0e30\u0e1e\u0e27\u0e01 Skater \u0e17\u0e35\u0e48\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e40\u0e1e\u0e25\u0e07 Hiphop \u0e21\u0e32\u0e40\u0e1b\u0e47\u0e19 Soundtrack<br \/>\n\u0e02\u0e2d\u0e07\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07\u0e15\u0e2d\u0e19\u0e40\u0e25\u0e48\u0e19\u0e01\u0e47\u0e08\u0e30\u0e21\u0e35 Style \u0e01\u0e32\u0e23\u0e41\u0e15\u0e48\u0e07\u0e15\u0e31\u0e27\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e0a\u0e2d\u0e1a\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32\u0e14\u0e49\u0e27\u0e22<br \/>\n\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e0a\u0e48\u0e19 Josh Kalis \u0e01\u0e31\u0e1a Stevie Williams \u0e17\u0e31\u0e49\u0e07\u0e2a\u0e2d\u0e07\u0e04\u0e19\u0e19\u0e31\u0e49\u0e19\u0e40\u0e25\u0e48\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48<br \/>\nLOVE PARK Philladelphia \u0e1e\u0e2d\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1b\u0e27\u0e0a. \u0e08\u0e1a \u0e01\u0e47\u0e04\u0e34\u0e14\u0e27\u0e48\u0e32\u0e2d\u0e22\u0e32\u0e01\u0e08\u0e30\u0e44\u0e1b\u0e40\u0e25\u0e48\u0e19Skate \u0e17\u0e35\u0e48\u0e19\u0e31\u0e48\u0e19\u0e17\u0e31\u0e19\u0e17\u0e35<\/p>\n<p><a href=\"http:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball2.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-323\" src=\"http:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball2-600x600.jpg\" alt=\"ball2\" width=\"600\" height=\"600\" srcset=\"https:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball2-600x600.jpg 600w, https:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball2-300x300.jpg 300w, https:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball2-305x305.jpg 305w, https:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball2.jpg 640w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p><strong><br \/>\nQ : \u0e01\u0e47\u0e40\u0e25\u0e22\u0e44\u0e1b\u0e25\u0e38\u0e22\u0e2d\u0e40\u0e21\u0e23\u0e34\u0e01\u0e32\u0e0b\u0e30\u0e40\u0e25\u0e22?<\/strong><\/p>\n<p>A : \u0e1e\u0e2d\u0e44\u0e14\u0e49\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e44\u0e1b\u0e41\u0e25\u0e49\u0e27 \u0e21\u0e31\u0e19\u0e44\u0e21\u0e48\u0e2a\u0e19\u0e38\u0e01\u0e21\u0e31\u0e19\u0e44\u0e21\u0e48\u0e07\u0e48\u0e32\u0e22\u0e40\u0e25\u0e22<br \/>\n\u0e04\u0e37\u0e2d \u0e40\u0e23\u0e32\u0e0a\u0e2d\u0e1a\u0e40\u0e25\u0e48\u0e19\u0e01\u0e35\u0e2c\u0e32\u0e41\u0e15\u0e48\u0e40\u0e14\u0e47\u0e01 \u0e0a\u0e2d\u0e1a\u0e40\u0e25\u0e48\u0e19\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u0e40\u0e25\u0e48\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e21\u0e14<br \/>\n\u0e14\u0e39\u0e01\u0e35\u0e2c\u0e32\u0e17\u0e38\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e1b\u0e34\u0e07\u0e1b\u0e2d\u0e07\u0e22\u0e31\u0e19\u0e42\u0e2d\u0e25\u0e34\u0e21\u0e1b\u0e34\u0e01\u0e24\u0e14\u0e39\u0e2b\u0e19\u0e32\u0e27<br \/>\n\u0e21\u0e31\u0e19\u0e04\u0e37\u0e2d\u0e40\u0e2b\u0e15\u0e38\u0e1c\u0e25\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e0a\u0e2d\u0e1a\u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e32\u0e21\u0e15\u0e33\u0e23\u0e32 \u0e41\u0e25\u0e30\u0e19\u0e31\u0e48\u0e19\u0e01\u0e47\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e2b\u0e48\u0e27\u0e22\u0e21\u0e32\u0e01<br \/>\n\u0e44\u0e1b\u0e16\u0e36\u0e07\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29 \u0e1e\u0e39\u0e14\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e40\u0e25\u0e22 \u0e04\u0e27\u0e32\u0e21\u0e1d\u0e31\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19 Skateboard \u0e40\u0e23\u0e34\u0e48\u0e21\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e41\u0e25\u0e30<br \/>\n\u0e40\u0e23\u0e32\u0e21\u0e32\u0e17\u0e35\u0e48\u0e19\u0e35\u0e48\u0e08\u0e30\u0e40\u0e25\u0e48\u0e19 Skate \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27\u0e21\u0e31\u0e19\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48 \u0e01\u0e48\u0e2d\u0e19\u0e2d\u0e37\u0e48\u0e19\u0e40\u0e25\u0e22\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e48\u0e2d\u0e19<br \/>\n\u0e41\u0e25\u0e30\u0e1a\u0e49\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e2d\u0e22\u0e39\u0e48\u0e44\u0e01\u0e25\u0e08\u0e32\u0e01\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e0b\u0e36\u0e48\u0e07\u0e42\u0e23\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e41\u0e25\u0e30<br \/>\nLOVE PARK \u0e01\u0e47\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e17\u0e38\u0e01\u0e27\u0e31\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e15\u0e37\u0e48\u0e19 6 \u0e42\u0e21\u0e07 \u0e40\u0e14\u0e34\u0e19\u0e17\u0e19\u0e2b\u0e19\u0e32\u0e27\u0e21\u0e32\u0e23\u0e2d\u0e23\u0e16\u0e40\u0e21\u0e22\u0e4c<br \/>\n\u0e15\u0e48\u0e2d\u0e23\u0e16\u0e44\u0e1f\u0e44\u0e1b\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e0b\u0e36\u0e48\u0e07\u0e25\u0e33\u0e1a\u0e32\u0e01\u0e21\u0e32\u0e01 \u0e15\u0e2d\u0e19\u0e19\u0e31\u0e49\u0e19\u0e15\u0e31\u0e49\u0e07\u0e43\u0e08\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2a\u0e38\u0e14\u0e02\u0e35\u0e14<br \/>\n\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e30\u0e40\u0e2d\u0e32\u0e20\u0e32\u0e29\u0e32 \u0e41\u0e25\u0e30\u0e01\u0e47\u0e40\u0e23\u0e34\u0e48\u0e21\u0e44\u0e14\u0e49\u0e1f\u0e31\u0e07\u0e40\u0e1e\u0e25\u0e07 Hiphop \u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19<br \/>\n\u0e1f\u0e31\u0e07\u0e04\u0e25\u0e37\u0e48\u0e19\u0e27\u0e34\u0e17\u0e22\u0e38\u0e17\u0e35\u0e48\u0e19\u0e31\u0e48\u0e19\u0e15\u0e25\u0e2d\u0e14 \u0e1d\u0e36\u0e01\u0e20\u0e32\u0e29\u0e32 \u201cSlang\u201d \u0e14\u0e39\u0e2b\u0e19\u0e31\u0e07\u0e27\u0e31\u0e22\u0e23\u0e38\u0e48\u0e19\u0e2d\u0e40\u0e21\u0e23\u0e34\u0e01\u0e31\u0e19<br \/>\n\u0e2d\u0e22\u0e48\u0e32\u0e07 American Pie \u0e14\u0e39\u0e41\u0e25\u0e49\u0e27\u0e14\u0e39\u0e2d\u0e35\u0e01 \u0e2d\u0e22\u0e32\u0e01\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08 \u201cSlang\u201d \u0e02\u0e2d\u0e07\u0e21\u0e31\u0e19\u0e41\u0e25\u0e49\u0e27<br \/>\n\u0e1e\u0e2d\u0e40\u0e23\u0e34\u0e48\u0e21\u0e2d\u0e34\u0e19\u0e01\u0e31\u0e1a\u0e21\u0e31\u0e19\u0e21\u0e32\u0e01\u0e46 \u0e01\u0e47\u0e40\u0e23\u0e34\u0e48\u0e21\u0e2d\u0e22\u0e32\u0e01\u0e17\u0e33\u0e40\u0e1e\u0e25\u0e07 \u0e2d\u0e22\u0e32\u0e01\u0e40\u0e1b\u0e47\u0e19 Dj<br \/>\n\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e01\u0e25\u0e31\u0e1a\u0e44\u0e1b\u0e40\u0e25\u0e48\u0e19 Skateboard \u0e43\u0e2b\u0e21\u0e48\u0e2d\u0e35\u0e01\u0e04\u0e23\u0e31\u0e49\u0e07<br \/>\n\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e04\u0e23\u0e32\u0e27 Dj \u0e01\u0e47\u0e44\u0e1b\u0e0b\u0e37\u0e49\u0e2d\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e31\u0e1a Vcd \u0e21\u0e32\u0e14\u0e39 (\u0e22\u0e38\u0e04\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19)<br \/>\n\u0e2b\u0e31\u0e14\u0e16\u0e39\u0e44\u0e16\u0e40\u0e2d\u0e32 \u0e41\u0e15\u0e48\u0e01\u0e47\u0e44\u0e21\u0e48\u0e21\u0e35\u0e04\u0e19\u0e2a\u0e2d\u0e19\u0e21\u0e32\u0e01\u0e19\u0e31\u0e01 \u0e41\u0e25\u0e30\u0e01\u0e47\u0e40\u0e23\u0e34\u0e48\u0e21\u0e2b\u0e31\u0e14 Rap \u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22<\/p>\n<p><strong><a href=\"http:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball3.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-324\" src=\"http:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball3-600x600.jpg\" alt=\"ball3\" width=\"600\" height=\"600\" srcset=\"https:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball3-600x600.jpg 600w, https:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball3-300x300.jpg 300w, https:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball3-305x305.jpg 305w, https:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball3.jpg 640w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/strong><br \/>\n<strong>Q : \u0e41\u0e25\u0e49\u0e27\u0e43\u0e0a\u0e49\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e2d\u0e22\u0e39\u0e48\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e15\u0e25\u0e2d\u0e14\u0e41\u0e1a\u0e1a\u0e19\u0e35\u0e49 \u0e44\u0e14\u0e49\u0e1f\u0e31\u0e07 Hiphop \u0e43\u0e19\u0e44\u0e17\u0e22\u0e1a\u0e49\u0e32\u0e07\u0e23\u0e36\u0e1b\u0e25\u0e48\u0e32\u0e27?<\/strong><\/p>\n<p>A : \u0e15\u0e2d\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48\u0e19\u0e31\u0e48\u0e19 \u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e41\u0e15\u0e48 Joeyboy \u0e14\u0e32\u0e08\u0e34\u0e21 \u0e01\u0e47\u0e1e\u0e36\u0e48\u0e07\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e15\u0e2d\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e44\u0e17\u0e22<br \/>\n\u0e19\u0e31\u0e48\u0e19\u0e21\u0e31\u0e19\u0e1b\u0e35 2003 \u0e19\u0e30\u0e17\u0e35\u0e48\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32<\/p>\n<p><a href=\"http:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball4.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-326\" src=\"http:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball4-600x600.jpg\" alt=\"ball4\" width=\"600\" height=\"600\" srcset=\"https:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball4-600x600.jpg 600w, https:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball4-300x300.jpg 300w, https:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball4-305x305.jpg 305w, https:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball4.jpg 640w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p><strong>Q : \u0e17\u0e35\u0e48\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e1a\u0e2d\u0e25\u0e08\u0e23\u0e34\u0e07\u0e46 \u0e40\u0e25\u0e22 \u0e04\u0e37\u0e2d\u0e15\u0e2d\u0e19\u0e17\u0e33\u0e40\u0e1e\u0e25\u0e07\u0e43\u0e19 Mixtape Thaitay<\/strong><br \/>\n<strong> \u0e40\u0e25\u0e48\u0e32\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e15\u0e2d\u0e19\u0e19\u0e31\u0e49\u0e19\u0e43\u0e2b\u0e49\u0e1f\u0e31\u0e07\u0e2b\u0e19\u0e48\u0e2d\u0e22\u0e2e\u0e30?<\/strong><\/p>\n<p>A : \u0e15\u0e2d\u0e19\u0e17\u0e33 Thaitanium Mixtape \u0e01\u0e47\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e2a\u0e19\u0e38\u0e01\u0e14\u0e35 \u0e21\u0e31\u0e19\u0e40\u0e01\u0e34\u0e14\u0e21\u0e32\u0e08\u0e32\u0e01<br \/>\n\u0e15\u0e2d\u0e19\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e08\u0e32\u0e01\u0e40\u0e21\u0e01\u0e32 \u0e40\u0e23\u0e32\u0e01\u0e47\u0e41\u0e1a\u0e1a \u0e40\u0e23\u0e32\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e41\u0e23\u0e07\u0e1a\u0e31\u0e19\u0e14\u0e32\u0e25\u0e43\u0e08\u0e21\u0e32\u0e41\u0e1a\u0e1a\u0e2a\u0e38\u0e14\u0e46\u0e2d\u0e48\u0e30<br \/>\n\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e01\u0e47\u0e15\u0e49\u0e2d\u0e07\u0e2d\u0e22\u0e32\u0e01\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e1b\u0e25\u0e48\u0e2d\u0e22\u0e02\u0e2d\u0e07 \u0e2d\u0e22\u0e32\u0e01\u0e17\u0e33\u0e40\u0e1e\u0e25\u0e07 \u0e41\u0e25\u0e30\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e46\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e17\u0e22\u0e32<br \/>\n\u0e01\u0e47\u0e21\u0e35\u0e40\u0e2d\u0e32\u0e14\u0e49\u0e27\u0e22\u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19 \u0e01\u0e47\u0e40\u0e25\u0e22\u0e40\u0e01\u0e34\u0e14 W2DE \u0e43\u0e19 Thaitanium Mixtape Vol.3<br \/>\n\u0e15\u0e2d\u0e19\u0e19\u0e31\u0e49\u0e19\u0e15\u0e25\u0e01\u0e2a\u0e38\u0e14\u0e46 \u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e27\u0e48\u0e32\u0e17\u0e33\u0e44\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e17\u0e33\u0e40\u0e1e\u0e25\u0e07 \u201cRepresent\u201d<br \/>\n\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e1e\u0e25\u0e07\u0e41\u0e23\u0e01<\/p>\n<p><strong>Q : 55555 \u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e17\u0e38\u0e01\u0e04\u0e19\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e04\u0e22\u0e1c\u0e48\u0e32\u0e19\u0e40\u0e25\u0e22\u0e0b\u0e34\u0e19\u0e30 &#8220;Represent&#8221; \u0e19\u0e35\u0e48\u2026<\/strong><\/p>\n<p>A : \u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e21\u0e31\u0e19\u0e21\u0e35\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e19\u0e31\u0e49\u0e19 555<\/p>\n<p><a href=\"http:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball5.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-327\" src=\"http:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball5-600x563.jpg\" alt=\"ball5\" width=\"600\" height=\"563\" srcset=\"https:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball5-600x563.jpg 600w, https:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball5-305x286.jpg 305w, https:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball5.jpg 720w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p><strong>Q : \u0e41\u0e25\u0e49\u0e27\u0e1a\u0e2d\u0e25\u0e01\u0e47\u0e21\u0e31\u0e19\u0e23\u0e31\u0e19 Siamhiphop.com \u0e15\u0e2d\u0e19\u0e19\u0e31\u0e49\u0e19\u0e21\u0e35\u0e40\u0e1b\u0e47\u0e19 \u201cAudio Battle\u201d<\/strong><br \/>\n<strong> \u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e2a\u0e40\u0e15\u0e47\u0e1b\u0e44\u0e1b\u0e2d\u0e35\u0e01\u0e02\u0e31\u0e49\u0e19\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23 Battle \u0e1c\u0e48\u0e32\u0e19\u0e2d\u0e34\u0e19\u0e40\u0e15\u0e2d\u0e23\u0e4c\u0e40\u0e19\u0e15\u0e2a\u0e21\u0e31\u0e22\u0e19\u0e31\u0e49\u0e19\u0e40\u0e25\u0e22\u0e19\u0e34?<\/strong><\/p>\n<p>A : Siamhiphop.com \u0e40\u0e23\u0e34\u0e48\u0e21\u0e08\u0e32\u0e01\u0e1a\u0e2d\u0e25\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27 \u0e17\u0e33\u0e40\u0e27\u0e47\u0e1a \u0e41\u0e1b\u0e25\u0e02\u0e48\u0e32\u0e27<br \/>\n\u0e15\u0e2d\u0e19\u0e19\u0e31\u0e49\u0e19\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e40\u0e23\u0e35\u0e22\u0e19\u0e15\u0e48\u0e2d\u0e21\u0e2b\u0e32\u0e25\u0e31\u0e22 \u0e1e\u0e25\u0e31\u0e07\u0e40\u0e2b\u0e25\u0e37\u0e2d \u0e41\u0e25\u0e30\u0e01\u0e47\u0e40\u0e23\u0e34\u0e48\u0e21\u0e21\u0e35\u0e19\u0e49\u0e2d\u0e07\u0e46\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e0a\u0e48\u0e27\u0e22<br \/>\n\u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19\u0e21\u0e32\u0e01\u0e02\u0e36\u0e49\u0e19 \u0e40\u0e23\u0e32 Meeting \u0e01\u0e31\u0e19\u0e44\u0e21\u0e48\u0e1a\u0e48\u0e2d\u0e22 \u0e40\u0e23\u0e32\u0e41\u0e1a\u0e48\u0e07\u0e07\u0e32\u0e19\u0e01\u0e31\u0e19<br \/>\n\u0e40\u0e04\u0e49\u0e32\u0e04\u0e38\u0e22\u0e01\u0e31\u0e19\u0e43\u0e19 msn \u0e15\u0e25\u0e2d\u0e14 \u0e04\u0e37\u0e2d\u0e22\u0e38\u0e04\u0e17\u0e2d\u0e07\u0e22\u0e38\u0e04\u0e41\u0e23\u0e01\u0e46 \u0e02\u0e2d\u0e07 Internet \u0e40\u0e25\u0e22\u0e08\u0e23\u0e34\u0e07\u0e46<br \/>\n\u0e43\u0e19 Siamhiphop.com \u0e21\u0e35\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22 \u0e40\u0e23\u0e34\u0e48\u0e21\u0e08\u0e32\u0e01\u0e41\u0e04\u0e48\u0e21\u0e35\u0e02\u0e48\u0e32\u0e27\u0e41\u0e1b\u0e25<br \/>\n\u0e41\u0e19\u0e30\u0e19\u0e33\u0e40\u0e1e\u0e25\u0e07 \u0e08\u0e19\u0e21\u0e35 Text Battle, Audio Battle \u0e08\u0e19\u0e16\u0e36\u0e07 Album \u0e41\u0e25\u0e30 Hiphop Party<br \/>\n\u0e17\u0e35\u0e48\u0e21\u0e35\u0e41\u0e02\u0e48\u0e07 Rap Battle \u0e14\u0e49\u0e27\u0e22 \u0e0a\u0e48\u0e27\u0e07\u0e19\u0e31\u0e49\u0e19\u0e04\u0e19\u0e40\u0e23\u0e34\u0e48\u0e21\u0e2a\u0e19\u0e43\u0e08 Hiphop \u0e40\u0e23\u0e34\u0e48\u0e21\u0e40\u0e22\u0e2d\u0e30<br \/>\n\u0e1c\u0e31\u0e1a\u0e1a\u0e32\u0e23\u0e4c\u0e40\u0e23\u0e34\u0e48\u0e21\u0e2d\u0e22\u0e32\u0e01\u0e43\u0e2b\u0e49\u0e40\u0e23\u0e32\u0e44\u0e1b\u0e08\u0e31\u0e14\u0e1b\u0e32\u0e23\u0e4c\u0e15\u0e35\u0e49 (\u0e15\u0e2d\u0e19\u0e19\u0e31\u0e49\u0e19\u0e1c\u0e31\u0e1a\u0e1a\u0e32\u0e23\u0e4c\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e25\u0e48\u0e19\u0e2a\u0e14 \u0e01\u0e31\u0e1a\u0e1e\u0e27\u0e01\u0e40\u0e1e\u0e25\u0e07 Electronic )<br \/>\n\u0e41\u0e25\u0e30\u0e01\u0e47\u0e2b\u0e49\u0e32\u0e07\u0e21\u0e32\u0e1a\u0e38\u0e0d\u0e04\u0e23\u0e2d\u0e07\u0e01\u0e47\u0e43\u0e2b\u0e49\u0e40\u0e23\u0e32\u0e44\u0e1b\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19 Hiphop \u0e43\u0e2b\u0e49\u0e2b\u0e25\u0e32\u0e22\u0e15\u0e48\u0e2d\u0e2b\u0e25\u0e32\u0e22\u0e04\u0e23\u0e31\u0e49\u0e07<\/p>\n<p><a href=\"http:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball6.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-328\" src=\"http:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball6-600x600.jpg\" alt=\"ball6\" width=\"600\" height=\"600\" srcset=\"https:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball6-600x600.jpg 600w, https:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball6-300x300.jpg 300w, https:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball6-305x305.jpg 305w, https:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball6.jpg 640w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p><strong>Q : \u0e41\u0e25\u0e49\u0e27\u0e17\u0e33\u0e44\u0e21\u0e08\u0e39\u0e48\u0e46 \u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e1a\u0e2d\u0e25\u0e40\u0e23\u0e34\u0e48\u0e21\u0e40\u0e08\u0e30\u0e19\u0e34\u0e48\u0e07\u0e46\u0e44\u0e1b\u0e23\u0e36\u0e1b\u0e25\u0e48\u0e32\u0e27 \u0e2b\u0e23\u0e37\u0e2d\u0e17\u0e33\u0e2d\u0e30\u0e44\u0e23\u0e1a\u0e49\u0e32\u0e07\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e19\u0e31\u0e49\u0e19<\/strong><br \/>\n<strong>\u0e40\u0e25\u0e48\u0e32\u0e43\u0e2b\u0e49\u0e1f\u0e31\u0e07\u0e2b\u0e19\u0e48\u0e2d\u0e22\u0e2e\u0e30\u0e01\u0e27\u0e48\u0e32\u0e08\u0e30\u0e21\u0e32\u0e40\u0e1b\u0e47\u0e19 &#8220;SneakaVilla&#8221;?<\/strong><\/p>\n<p>A : \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e40\u0e25\u0e48\u0e19 Skateboard \u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e19\u0e1a\u0e49\u0e32\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e41\u0e25\u0e49\u0e27<br \/>\n\u0e1e\u0e2d\u0e21\u0e32\u0e1a\u0e49\u0e32 Hiphop \u0e01\u0e47\u0e1a\u0e49\u0e32\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e44\u0e21\u0e48\u0e0a\u0e2d\u0e1a\u0e43\u0e2a\u0e48\u0e0b\u0e49\u0e33\u0e43\u0e04\u0e23 \u0e0a\u0e2d\u0e1a\u0e19\u0e33\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19<br \/>\n\u0e08\u0e30\u0e2b\u0e32\u0e2a\u0e31\u0e48\u0e07\u0e08\u0e32\u0e01\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e19\u0e2d\u0e01\u0e21\u0e32 \u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32\u0e15\u0e49\u0e2d\u0e07 Limited \u0e2d\u0e30\u0e44\u0e23\u0e41\u0e1a\u0e1a\u0e40\u0e19\u0e35\u0e49\u0e22<br \/>\n\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e46 \u0e01\u0e47\u0e40\u0e23\u0e34\u0e48\u0e21\u0e21\u0e32\u0e02\u0e2d\u0e0b\u0e37\u0e49\u0e2d\u0e15\u0e48\u0e2d \u0e41\u0e25\u0e30\u0e01\u0e47\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19<br \/>\n\u0e40\u0e23\u0e32\u0e01\u0e47\u0e40\u0e23\u0e34\u0e48\u0e21\u0e2a\u0e31\u0e48\u0e07\u0e21\u0e32\u0e43\u0e2b\u0e49 \u0e2a\u0e31\u0e48\u0e07\u0e21\u0e32\u0e02\u0e32\u0e22\u0e40\u0e04\u0e49\u0e32 \u0e01\u0e47\u0e40\u0e25\u0e22\u0e2d\u0e22\u0e32\u0e01\u0e40\u0e1b\u0e34\u0e14\u0e23\u0e49\u0e32\u0e19<br \/>\n\u0e41\u0e25\u0e30\u0e01\u0e47\u0e17\u0e33\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e43\u0e2b\u0e49\u0e21\u0e31\u0e19 Match \u0e01\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e02\u0e32\u0e22<br \/>\n\u0e19\u0e31\u0e48\u0e19\u0e04\u0e37\u0e2d Idea \u0e02\u0e2d\u0e07 SneakaVilla \u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19<br \/>\n\u0e41\u0e25\u0e30\u0e15\u0e2d\u0e19\u0e19\u0e31\u0e49\u0e19\u0e40\u0e23\u0e32\u0e01\u0e47\u0e40\u0e23\u0e34\u0e48\u0e21\u0e42\u0e15\u0e02\u0e36\u0e49\u0e19\u0e14\u0e49\u0e27\u0e22 \u0e1e\u0e2d\u0e40\u0e23\u0e32\u0e40\u0e25\u0e48\u0e19\u0e23\u0e2d\u0e07\u0e40\u0e17\u0e49\u0e32<br \/>\n\u0e40\u0e25\u0e48\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 \u0e21\u0e31\u0e19\u0e01\u0e47\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e34\u0e14 \u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e2a\u0e1e\u0e22\u0e4c Street Art \u0e02\u0e2d\u0e07\u0e40\u0e25\u0e48\u0e19\u0e2d\u0e35\u0e01<br \/>\n\u0e40\u0e23\u0e34\u0e48\u0e21\u0e2a\u0e19\u0e38\u0e01\u0e0a\u0e48\u0e27\u0e07\u0e41\u0e23\u0e01\u0e46 \u0e01\u0e47\u0e22\u0e31\u0e07\u0e17\u0e33 Siamhiphop \u0e04\u0e27\u0e1a\u0e04\u0e39\u0e48\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22<br \/>\n\u0e0a\u0e48\u0e27\u0e07\u0e2b\u0e25\u0e31\u0e07\u0e46\u0e44\u0e1b\u0e17\u0e33\u0e40\u0e27\u0e47\u0e1a\u0e43\u0e2b\u0e21\u0e48\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e01\u0e47\u0e40\u0e25\u0e22\u0e44\u0e1b\u0e21\u0e38\u0e48\u0e07\u0e21\u0e31\u0e48\u0e19<br \/>\n\u0e01\u0e31\u0e1a\u0e15\u0e23\u0e07\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e23\u0e32\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32 \u0e40\u0e1e\u0e23\u0e32\u0e30 Rapper<br \/>\n\u0e43\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e44\u0e17\u0e22\u0e15\u0e49\u0e2d\u0e07\u0e22\u0e2d\u0e21\u0e23\u0e31\u0e1a\u0e27\u0e48\u0e32\u0e2a\u0e21\u0e31\u0e22\u0e19\u0e31\u0e49\u0e19\u0e2b\u0e32\u0e01\u0e34\u0e19\u0e22\u0e32\u0e01\u0e21\u0e32\u0e01<\/p>\n<p><strong><a href=\"http:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball7.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-329\" src=\"http:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball7-600x600.jpg\" alt=\"ball7\" width=\"600\" height=\"600\" srcset=\"https:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball7-600x600.jpg 600w, https:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball7-300x300.jpg 300w, https:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball7-305x305.jpg 305w, https:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball7.jpg 800w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><br \/>\nQ : \u0e02\u0e2d\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e1a\u0e49\u0e32\u0e07&#8230; \u0e15\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e1a\u0e2d\u0e25\u0e17\u0e33\u0e2d\u0e30\u0e44\u0e23\u0e1a\u0e49\u0e32\u0e07<br \/>\n\u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07 SneakaVilla?<\/strong><\/p>\n<p>A : \u0e13 \u0e15\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e40\u0e25\u0e22\u0e01\u0e47\u0e40\u0e1b\u0e47\u0e19 Creative Director \u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a SneakaVilla<\/p>\n<p>\u0e41\u0e25\u0e30\u0e1a\u0e2d\u0e25\u0e01\u0e31\u0e1a\u0e20\u0e23\u0e23\u0e22\u0e32\u0e01\u0e47\u0e17\u0e33\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e0a\u0e37\u0e48\u0e2d Passion Juice \u0e40\u0e1b\u0e47\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17<br \/>\n\u0e17\u0e35\u0e48\u0e17\u0e33\u0e07\u0e32\u0e19 Creative Marketing \u0e17\u0e35\u0e48\u0e16\u0e19\u0e31\u0e14\u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e41\u0e15\u0e48\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19<br \/>\nLifestyle \u0e01\u0e31\u0e1a Fashion \u0e17\u0e33\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48 Branding \u0e44\u0e1b\u0e22\u0e31\u0e19 Event \u0e41\u0e25\u0e30 Party<\/p>\n<p><a href=\"http:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball8.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-330\" src=\"http:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball8-600x600.jpg\" alt=\"ball8\" width=\"600\" height=\"600\" srcset=\"https:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball8-600x600.jpg 600w, https:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball8-300x300.jpg 300w, https:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball8-305x305.jpg 305w, https:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball8.jpg 640w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p><strong>Q : \u0e15\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e08\u0e31\u0e14\u0e44\u0e14\u0e49\u0e27\u0e48\u0e32\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e01\u0e31\u0e1a\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e35\u0e48\u0e15\u0e31\u0e49\u0e07\u0e40\u0e2d\u0e32\u0e44\u0e27\u0e49\u0e23\u0e36\u0e22\u0e31\u0e07<\/strong><br \/>\n<strong>\u0e41\u0e25\u0e49\u0e27\u0e21\u0e35\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e2d\u0e35\u0e01\u0e23\u0e36\u0e1b\u0e25\u0e48\u0e32\u0e27?<\/strong><\/p>\n<p>A : \u0e40\u0e2d\u0e32\u0e08\u0e23\u0e34\u0e07\u0e46 \u0e01\u0e47\u0e16\u0e37\u0e2d\u0e27\u0e48\u0e32\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32\u0e17\u0e35\u0e48\u0e04\u0e34\u0e14\u0e44\u0e27\u0e49\u0e19\u0e30<br \/>\n\u0e44\u0e21\u0e48\u0e40\u0e04\u0e22\u0e04\u0e34\u0e14\u0e27\u0e48\u0e32\u0e08\u0e30\u0e21\u0e32\u0e44\u0e14\u0e49\u0e44\u0e01\u0e25\u0e02\u0e19\u0e32\u0e14\u0e19\u0e35\u0e49 \u0e41\u0e15\u0e48\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e2b\u0e25\u0e31\u0e01\u0e01\u0e47\u0e04\u0e37\u0e2d SneakaVilla<br \/>\n\u0e40\u0e1e\u0e23\u0e32\u0e30\u0e40\u0e23\u0e32\u0e17\u0e33\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e41\u0e23\u0e01 \u0e21\u0e31\u0e19\u0e04\u0e37\u0e2d Passion \u0e41\u0e25\u0e30\u0e40\u0e23\u0e32\u0e01\u0e47\u0e04\u0e34\u0e14\u0e44\u0e27\u0e49\u0e15\u0e25\u0e2d\u0e14\u0e27\u0e48\u0e32\u0e2d\u0e22\u0e32\u0e01\u0e43\u0e2b\u0e49\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c<br \/>\n\u0e1e\u0e2d\u0e21\u0e35\u0e17\u0e35\u0e48\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e43\u0e19\u0e44\u0e17\u0e22\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e21\u0e32\u0e01\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e01\u0e48\u0e2d\u0e19 \u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e19\u0e31\u0e01\u0e21\u0e27\u0e22 \u0e2b\u0e23\u0e37\u0e2d\u0e19\u0e31\u0e01\u0e1a\u0e2d\u0e25<br \/>\n\u0e16\u0e49\u0e32\u0e08\u0e30\u0e44\u0e1b\u0e40\u0e01\u0e48\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e1b\u0e15\u0e48\u0e2d\u0e22\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e19\u0e2d\u0e01 \u0e01\u0e47\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e01\u0e48\u0e07\u0e43\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e01\u0e48\u0e2d\u0e19 \u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e15\u0e48\u0e2d\u0e44\u0e1b<br \/>\n\u0e01\u0e47\u0e08\u0e30\u0e02\u0e22\u0e32\u0e22\u0e10\u0e32\u0e19\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e44\u0e1b\u0e22\u0e31\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e1a\u0e49\u0e32\u0e19\u00a0<span style=\"line-height: 1.5;\">\u0e41\u0e25\u0e30\u0e43\u0e19\u0e22\u0e38\u0e42\u0e23\u0e1b\u0e15\u0e48\u0e2d\u0e44\u0e1b<br \/>\n\u0e41\u0e25\u0e30\u0e08\u0e30\u0e17\u0e33\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c Sneaka Kids \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e40\u0e14\u0e47\u0e01 \u0e41\u0e25\u0e30\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e2b\u0e0d\u0e34\u0e07\u0e14\u0e49\u0e27\u0e22<\/span><\/p>\n<p><a href=\"http:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball9.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-331\" src=\"http:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball9-600x600.jpg\" alt=\"ball9\" width=\"600\" height=\"600\" srcset=\"https:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball9-600x600.jpg 600w, https:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball9-300x300.jpg 300w, https:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball9-305x305.jpg 305w, https:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball9.jpg 640w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p><strong>Q : \u0e1e\u0e39\u0e14\u0e16\u0e36\u0e07\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32\u0e40\u0e14\u0e47\u0e01\u0e15\u0e2d\u0e19\u0e19\u0e35\u0e49\u0e21\u0e35\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27\u0e21\u0e35\u0e25\u0e39\u0e01\u0e15\u0e31\u0e27\u0e19\u0e49\u0e2d\u0e22\u0e41\u0e25\u0e49\u0e27<br \/>\n<\/strong><strong><span style=\"line-height: 1.5;\">\u0e1a\u0e2d\u0e25\u0e21\u0e35\u0e21\u0e38\u0e21\u0e21\u0e2d\u0e07\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e15\u0e48\u0e32\u0e07\u0e08\u0e32\u0e01\u0e40\u0e14\u0e34\u0e21\u0e1a\u0e49\u0e32\u0e07\u0e44\u0e2b\u0e21?<\/span><\/strong><\/p>\n<p>A : \u0e15\u0e48\u0e32\u0e07\u0e01\u0e31\u0e19\u0e41\u0e1a\u0e1a\u0e2a\u0e38\u0e14\u0e02\u0e31\u0e49\u0e27 \u0e44\u0e21\u0e48\u0e40\u0e04\u0e22\u0e04\u0e34\u0e14\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e48\u0e2d\u0e04\u0e19<br \/>\n\u0e2b\u0e23\u0e37\u0e2d\u0e2b\u0e31\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e22\u0e31\u0e07\u0e44\u0e07 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e01\u0e48\u0e2d\u0e19\u0e04\u0e34\u0e14\u0e41\u0e04\u0e48\u0e27\u0e48\u0e32\u0e40\u0e23\u0e32\u0e17\u0e33\u0e07\u0e32\u0e19<br \/>\n\u0e40\u0e23\u0e32\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e38\u0e02\u0e01\u0e31\u0e1a\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19 \u0e01\u0e31\u0e1a\u0e41\u0e1f\u0e19 \u0e41\u0e15\u0e48\u0e1e\u0e2d\u0e21\u0e35\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27\u0e41\u0e25\u0e49\u0e27\u0e21\u0e31\u0e19\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e41\u0e04\u0e48\u0e15\u0e31\u0e27\u0e40\u0e23\u0e32\u0e40\u0e2d\u0e07<br \/>\n\u0e04\u0e33\u0e27\u0e48\u0e32\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e23\u0e31\u0e27\u0e21\u0e31\u0e19\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32 2 \u0e04\u0e19 \u0e2b\u0e21\u0e32\u0e22\u0e16\u0e36\u0e07\u0e40\u0e23\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e23\u0e31\u0e1a\u0e1c\u0e34\u0e14\u0e0a\u0e2d\u0e1a\u0e21\u0e32\u0e01\u0e46<br \/>\n\u0e17\u0e38\u0e01\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e49\u0e2d\u0e07\u0e21\u0e35\u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e40\u0e23\u0e32\u0e01\u0e47\u0e2d\u0e22\u0e32\u0e01\u0e43\u0e2b\u0e49\u0e25\u0e39\u0e01\u0e21\u0e35\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e17\u0e35\u0e48\u0e14\u0e35<\/p>\n<p><a href=\"http:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball10.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-332\" src=\"http:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball10-600x405.jpg\" alt=\"ball10\" width=\"600\" height=\"405\" srcset=\"https:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball10-600x405.jpg 600w, https:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball10-305x206.jpg 305w, https:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball10.jpg 800w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><br \/>\n<\/a><\/p>\n<p><strong>Q : \u0e16\u0e49\u0e32\u0e43\u0e2b\u0e49\u0e21\u0e2d\u0e07 Hiphop \u0e44\u0e17\u0e22\u0e43\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e1a\u0e2d\u0e25\u0e04\u0e34\u0e14\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e1a\u0e49\u0e32\u0e07<\/strong><br \/>\n<strong><span style=\"line-height: 1.5;\">\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e01\u0e31\u0e1a\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e0b\u0e31\u0e01\u0e2a\u0e34\u0e1a\u0e01\u0e27\u0e48\u0e32\u0e1b\u0e35\u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32 \u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e1a\u0e2d\u0e25\u0e40\u0e23\u0e34\u0e48\u0e21\u0e40\u0e02\u0e49\u0e32\u0e27\u0e07\u0e01\u0e32\u0e23\u0e43\u0e2b\u0e21\u0e48\u0e46?<\/span><\/strong><\/p>\n<p>A : \u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e2b\u0e23\u0e37\u0e2d\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e16\u0e36\u0e07\u0e21\u0e31\u0e19\u0e07\u0e48\u0e32\u0e22\u0e02\u0e36\u0e49\u0e19<br \/>\n\u0e22\u0e38\u0e04\u0e19\u0e35\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e22\u0e38\u0e04\u0e17\u0e35\u0e48\u0e04\u0e19\u0e17\u0e33\u0e01\u0e31\u0e1a\u0e04\u0e19\u0e1f\u0e31\u0e07\u0e21\u0e31\u0e19\u0e15\u0e34\u0e14\u0e15\u0e48\u0e2d\u0e16\u0e36\u0e07\u0e01\u0e31\u0e19\u0e44\u0e14\u0e49\u0e40\u0e25\u0e22<br \/>\n\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e1c\u0e48\u0e32\u0e19\u0e15\u0e31\u0e27\u0e01\u0e25\u0e32\u0e07\u0e2b\u0e25\u0e32\u0e22\u0e46 \u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e43\u0e19\u0e22\u0e38\u0e04\u0e19\u0e31\u0e49\u0e19\u0e40\u0e0a\u0e48\u0e19 \u0e15\u0e49\u0e2d\u0e07\u0e1c\u0e48\u0e32\u0e19\u0e04\u0e48\u0e32\u0e22<br \/>\n\u0e1c\u0e48\u0e32\u0e19\u0e2a\u0e37\u0e48\u0e2d\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d \u0e17\u0e35\u0e48\u0e01\u0e47\u0e2b\u0e32\u0e0b\u0e37\u0e49\u0e2d\u0e22\u0e32\u0e01\u0e43\u0e19\u0e44\u0e17\u0e22 \u0e43\u0e19\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c\u0e01\u0e47\u0e22\u0e31\u0e07\u0e19\u0e49\u0e2d\u0e22<br \/>\n\u0e43\u0e19\u0e27\u0e34\u0e17\u0e22\u0e38\u0e19\u0e35\u0e48\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e04\u0e34\u0e14 \u0e41\u0e25\u0e30\u0e2a\u0e21\u0e31\u0e22\u0e19\u0e35\u0e49\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e01\u0e47\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e17\u0e33\u0e40\u0e1e\u0e25\u0e07 \u0e2d\u0e31\u0e14 Demo \u0e01\u0e31\u0e19\u0e07\u0e48\u0e32\u0e22\u0e02\u0e36\u0e49\u0e19<br \/>\n\u0e2a\u0e21\u0e31\u0e22\u0e19\u0e35\u0e49\u0e40\u0e25\u0e22\u0e21\u0e35\u0e28\u0e34\u0e25\u0e1b\u0e34\u0e19\u0e40\u0e01\u0e48\u0e07\u0e46\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e21\u0e32\u0e40\u0e22\u0e2d\u0e30\u0e21\u0e32\u0e01 \u0e41\u0e25\u0e30\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e07\u0e49\u0e2d\u0e04\u0e48\u0e32\u0e22\u0e14\u0e49\u0e27\u0e22<\/p>\n<p><span class=\"embed-youtube\" style=\"text-align:center; display: block;\"><iframe loading=\"lazy\" class=\"youtube-player\" width=\"640\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/--H8OMPcEGo?version=3&#038;rel=1&#038;showsearch=0&#038;showinfo=1&#038;iv_load_policy=1&#038;fs=1&#038;hl=en-US&#038;autohide=2&#038;wmode=transparent\" allowfullscreen=\"true\" style=\"border:0;\" sandbox=\"allow-scripts allow-same-origin allow-popups allow-presentation\"><\/iframe><\/span><\/p>\n<p><strong><br \/>\nQ : \u0e44\u0e14\u0e49\u0e02\u0e48\u0e32\u0e27\u0e1a\u0e2d\u0e25\u0e01\u0e47\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21 RAP IS NOW \u0e14\u0e49\u0e27\u0e22&#8230;<\/strong><br \/>\n<strong><span style=\"line-height: 1.5;\">\u0e08\u0e32\u0e01\u0e17\u0e35\u0e48\u0e04\u0e38\u0e22\u0e01\u0e31\u0e1a\u0e1a\u0e2d\u0e25\u0e21\u0e32\u0e19\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e23\u0e07\u0e1a\u0e31\u0e19\u0e14\u0e32\u0e25\u0e43\u0e08\u0e43\u0e2b\u0e49<br \/>\n<\/span><span style=\"line-height: 1.5;\">\u0e01\u0e31\u0e1a\u0e23\u0e38\u0e48\u0e19\u0e43\u0e2b\u0e21\u0e48\u0e46\u0e44\u0e14\u0e49\u0e44\u0e21\u0e48\u0e19\u0e49\u0e2d\u0e22\u0e40\u0e25\u0e22 \u0e21\u0e35\u0e2d\u0e30\u0e44\u0e23\u0e1e\u0e39\u0e14\u0e01\u0e31\u0e1a\u0e1e\u0e27\u0e01\u0e40\u0e04\u0e49\u0e32\u0e44\u0e2b\u0e21?<\/span><\/strong><\/p>\n<p>A : \u0e08\u0e31\u0e14\u0e07\u0e32\u0e19 Battle Mc \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e40\u0e27\u0e47\u0e1a\u0e44\u0e0b\u0e15\u0e4c \u0e41\u0e25\u0e30\u0e15\u0e32\u0e21\u0e07\u0e32\u0e19 Siamhiphop \u0e21\u0e32\u0e2b\u0e25\u0e32\u0e22\u0e15\u0e48\u0e2d\u0e2b\u0e25\u0e32\u0e22\u0e04\u0e23\u0e31\u0e49\u0e07<br \/>\n\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e44\u0e14\u0e49\u0e44\u0e1b\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23 Singha Battle of the Year \u0e21\u0e32\u0e1b\u0e35\u0e19\u0e36\u0e07<br \/>\n\u0e01\u0e32\u0e23\u0e41\u0e02\u0e48\u0e07 Rap Battle \u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e30\u0e44\u0e23\u0e17\u0e35\u0e48\u0e2a\u0e19\u0e38\u0e01\u0e21\u0e32\u0e01 \u0e22\u0e34\u0e48\u0e07\u0e23\u0e2d\u0e1a\u0e25\u0e36\u0e01\u0e46<br \/>\n\u0e40\u0e23\u0e32\u0e08\u0e30\u0e22\u0e34\u0e48\u0e07\u0e44\u0e14\u0e49\u0e1f\u0e31\u0e07\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e17\u0e35\u0e48\u0e21\u0e31\u0e19\u0e2a\u0e14 \u0e2b\u0e22\u0e34\u0e1a\u0e08\u0e32\u0e01\u0e2d\u0e30\u0e44\u0e23\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e47\u0e19 \u0e17\u0e35\u0e48\u0e2a\u0e27\u0e21\u0e43\u0e2a\u0e48<br \/>\n\u0e2d\u0e30\u0e44\u0e23\u0e17\u0e35\u0e48\u0e04\u0e34\u0e14\u0e2a\u0e14\u0e46 \u0e21\u0e32 Diss \u0e1d\u0e31\u0e48\u0e07\u0e15\u0e23\u0e07\u0e02\u0e49\u0e32\u0e21 \u0e17\u0e38\u0e01\u0e04\u0e23\u0e31\u0e49\u0e07\u0e43\u0e19\u0e23\u0e2d\u0e1a\u0e0a\u0e34\u0e07<br \/>\n\u0e40\u0e23\u0e32\u0e08\u0e30\u0e40\u0e2b\u0e47\u0e19\u0e2d\u0e30\u0e44\u0e23\u0e17\u0e35\u0e48\u0e21\u0e31\u0e19\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32\u0e41\u0e04\u0e48\u0e44\u0e1b\u0e01\u0e25\u0e31\u0e1a 2 \u0e23\u0e2d\u0e1a<br \/>\n\u0e21\u0e31\u0e19\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e21\u0e35\u0e41\u0e16\u0e21\u0e15\u0e25\u0e2d\u0e14 RAP IS NOW \u0e01\u0e47\u0e40\u0e0a\u0e48\u0e19\u0e01\u0e31\u0e19<\/p>\n<p><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-333\" src=\"http:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball11-600x600.jpg\" alt=\"ball11\" width=\"600\" height=\"600\" srcset=\"https:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball11-600x600.jpg 600w, https:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball11-300x300.jpg 300w, https:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball11-305x305.jpg 305w, https:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball11.jpg 640w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/p>\n<p><strong>Q : \u0e2a\u0e38\u0e14\u0e17\u0e49\u0e32\u0e22\u0e04\u0e07\u0e21\u0e35\u0e41\u0e1f\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e1a\u0e2d\u0e25\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e04\u0e23\u0e31\u0e49\u0e07\u0e2d\u0e22\u0e39\u0e48 W2DE<\/strong><br \/>\n<strong>\u0e27\u0e48\u0e32\u0e1a\u0e2d\u0e25\u0e08\u0e30\u0e21\u0e35\u0e1c\u0e25\u0e07\u0e32\u0e19\u0e40\u0e1e\u0e25\u0e07\u0e43\u0e2b\u0e21\u0e48\u0e1a\u0e49\u0e32\u0e07\u0e43\u0e2b\u0e49\u0e44\u0e14\u0e49\u0e1f\u0e31\u0e07\u0e1a\u0e49\u0e32\u0e07\u0e23\u0e36\u0e1b\u0e25\u0e48\u0e32\u0e27?<\/strong><\/p>\n<p>A : \u0e40\u0e04\u0e22\u0e04\u0e34\u0e14\u0e2d\u0e22\u0e39\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e17\u0e33\u0e40\u0e1e\u0e25\u0e07 \u0e04\u0e38\u0e22\u0e01\u0e31\u0e1a\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e46 \u0e14\u0e34\u0e1a\u0e14\u0e35 \u0e41\u0e15\u0e48\u0e1e\u0e2d\u0e21\u0e32\u0e14\u0e39\u0e15\u0e32\u0e23\u0e32\u0e07\u0e40\u0e27\u0e25\u0e32\u0e15\u0e31\u0e27\u0e40\u0e2d\u0e07<br \/>\n\u0e40\u0e23\u0e32\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e27\u0e48\u0e32\u0e07\u0e02\u0e19\u0e32\u0e14\u0e19\u0e31\u0e49\u0e19\u0e41\u0e25\u0e49\u0e27 \u0e41\u0e15\u0e48\u0e16\u0e49\u0e32\u0e21\u0e35\u0e40\u0e27\u0e25\u0e32\u0e27\u0e48\u0e32\u0e07\u0e01\u0e47\u0e2d\u0e22\u0e32\u0e01\u0e08\u0e30\u0e01\u0e25\u0e31\u0e1a\u0e21\u0e32\u0e17\u0e33 \u0e17\u0e33\u0e41\u0e1a\u0e1a Old Skool<br \/>\n\u0e41\u0e1a\u0e1a\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e0a\u0e2d\u0e1a\u0e1f\u0e31\u0e07 \u0e2a\u0e38\u0e14\u0e17\u0e49\u0e32\u0e22\u0e02\u0e2d\u0e02\u0e2d\u0e1a\u0e04\u0e38\u0e13\u0e1a\u0e17\u0e2a\u0e31\u0e21\u0e20\u0e32\u0e29\u0e13\u0e4c\u0e19\u0e35\u0e49 \u0e41\u0e25\u0e30 \u0e02\u0e2d\u0e1a\u0e04\u0e38\u0e13\u0e08\u0e32\u0e01\u0e43\u0e08\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e17\u0e35\u0e21\u0e07\u0e32\u0e19<br \/>\n\u0e17\u0e35\u0e48\u0e22\u0e31\u0e07\u0e04\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e23\u0e07\u0e1c\u0e25\u0e31\u0e01\u0e14\u0e31\u0e19\u0e43\u0e19\u0e01\u0e31\u0e1a\u0e40\u0e14\u0e47\u0e01 Rap \u0e17\u0e38\u0e01\u0e04\u0e19\u0e22\u0e31\u0e07\u0e21\u0e35\u0e40\u0e27\u0e17\u0e35\u0e17\u0e35\u0e48\u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16<br \/>\n\u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e2a\u0e19\u0e38\u0e01\u0e01\u0e31\u0e19\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e02\u0e2d\u0e07\u0e0a\u0e35\u0e27\u0e34\u0e15<\/p>\n<p><a href=\"http:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball12.jpg\"><img loading=\"lazy\" class=\"aligncenter size-medium wp-image-334\" src=\"http:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball12-600x400.jpg\" alt=\"ball12\" width=\"600\" height=\"400\" srcset=\"https:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball12-600x400.jpg 600w, https:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball12-1024x683.jpg 1024w, https:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball12-305x203.jpg 305w, https:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball12.jpg 2048w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/p>\n<p>\u0e08\u0e32\u0e01\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e1e\u0e39\u0e14\u0e04\u0e38\u0e22\u0e01\u0e31\u0e1a\u0e1a\u0e2d\u0e25\u0e21\u0e32\u0e14\u0e39\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e41\u0e23\u0e47\u0e1e\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e19\u0e31\u0e01\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e04\u0e19\u0e19\u0e35\u0e49\u0e41\u0e17\u0e1a\u0e08\u0e30<br \/>\n\u0e40\u0e23\u0e35\u0e22\u0e01\u0e44\u0e14\u0e49\u0e27\u0e48\u0e32\u0e2b\u0e19\u0e17\u0e32\u0e07\u0e42\u0e23\u0e22\u0e14\u0e49\u0e27\u0e22\u0e01\u0e23\u0e35\u0e1a\u0e01\u0e38\u0e2b\u0e25\u0e32\u0e1a..\u0e41\u0e15\u0e48\u0e43\u0e19\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e08\u0e23\u0e34\u0e07\u0e41\u0e25\u0e49\u0e27\u0e1a\u0e2d\u0e25<br \/>\n\u0e2b\u0e23\u0e37\u0e2d \u201cBallistic\u201d \u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e01\u0e31\u0e19\u0e43\u0e19\u0e17\u0e38\u0e01\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49 \u0e04\u0e07\u0e08\u0e30\u0e44\u0e21\u0e48\u0e2d\u0e32\u0e08\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08<br \/>\n\u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e22\u0e2d\u0e21\u0e23\u0e31\u0e1a\u0e44\u0e14\u0e49\u0e02\u0e19\u0e32\u0e14\u0e19\u0e35\u0e49\u0e2b\u0e32\u0e01\u0e41\u0e15\u0e48\u0e27\u0e48\u0e32\u0e40\u0e02\u0e32\u0e17\u0e33\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e41\u0e04\u0e48\u0e04\u0e34\u0e14\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27<\/p>\n<p><strong>\u0e08\u0e36\u0e07\u0e1e\u0e39\u0e14\u0e44\u0e14\u0e49\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e25\u0e07\u0e21\u0e37\u0e2d\u0e17\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e34\u0e48\u0e07\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e04\u0e34\u0e14\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19<\/strong><br \/>\n<strong> \u0e41\u0e25\u0e30\u0e19\u0e31\u0e48\u0e19\u0e04\u0e37\u0e2d Ballistic CEO \u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e14\u0e31\u0e07 SneakaVilla<\/strong><\/p>\n<p>Interview by : NaZe$u$<\/p>\n<p>Credit :\u00a0https:\/\/www.facebook.com\/ballisticone<\/p>\n<div class=\"_53\">\n<div class=\"_3hi clearfix\">\n<div class=\"_38 direction_ltr\">\n<p><a class=\"_553k\" href=\"http:\/\/www.ballisticone.com\/\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">www.ballisticone.com<br \/>\n<\/a> <a class=\"_553k\" href=\"http:\/\/instagram.com\/ballisticone\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">instagram.com\/ballisticone<br \/>\n<\/a> <a class=\"_553k\" href=\"https:\/\/www.facebook.com\/djballisticone?__mref=message\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">https:\/\/www.facebook.com\/djballisticone<\/a><br \/>\n<a class=\"_553k\" href=\"http:\/\/www.mixcloud.com\/ballisticone\/\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">www.mixcloud.com\/ballisticone\/<\/a><\/p>\n<\/div>\n<div class=\"_1yr\"><\/div>\n<\/div>\n<\/div>\n<div class=\"_sq\"><\/div>\n<p>&nbsp; <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ballistic \u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e09\u0e32\u0e22\u0e32 &#8220;\u0e40\u0e08\u0e49\u0e32\u0e1e\u0e48\u0e2d\u0e2a\u0e15\u0e23\u0e35\u0e17\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19&#8221; \u0e08\u0e32\u0e01\u0e41\u0e23\u0e47\u0e1e\u0e40\u0e1b\u0e2d\u0e23\u0e4c \u0e2a\u0e39\u0e48\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e08\u0e4b\u0e07\u0e46 \u0e17\u0e35\u0e48\u0e1c\u0e25\u0e31\u0e01\u0e14\u0e31\u0e19\u0e27\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e15\u0e23\u0e35\u0e17\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e19\u0e27\u0e07\u0e01\u0e32\u0e23\u2028\u0e2e\u0e34\u0e1e\u0e2e\u0e2d\u0e1e \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e22\u0e34\u0e19\u0e14\u0e35\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e40\u0e23\u0e32\u0e44\u0e14\u0e49\u0e21\u0e35\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e21\u0e32\u0e08\u0e31\u0e1a\u0e40\u0e02\u0e48\u0e32\u0e04\u0e38\u0e22\u0e01\u0e31\u0e1a Ballistic \u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e43\u0e19\u0e19\u0e32\u0e21\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 SneakaVilla \u0e40\u0e1b\u0e47\u0e19 DJ \u0e40\u0e1b\u0e47\u0e19\u0e04\u0e19\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19 Event \u0e15\u0e48\u0e32\u0e07\u0e46 &#8230; \u0e42\u0e2d\u0e48&#8230; \u0e17\u0e35\u0e48\u0e40\u0e2d\u0e48\u0e22\u0e21\u0e32\u0e04\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48 &#8220;\u0e41\u0e04\u0e48&#8221; \u0e0b\u0e30\u0e41\u0e25\u0e49\u0e27\u0e25\u0e48\u0e30&#8230; \u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e40\u0e23\u0e32\u0e21\u0e32\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e49\u0e32\u0e41\u0e1a\u0e1a\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e2a\u0e21\u0e31\u0e22\u0e27\u0e31\u0e22\u0e25\u0e30\u0e2d\u0e48\u0e2d\u0e19\u0e01\u0e31\u0e19\u0e14\u0e35\u0e01\u0e27\u0e48\u0e32&#8230; Q : \u0e1a\u0e2d\u0e25\u0e44\u0e14\u0e49\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e27\u0e07\u0e01\u0e32\u0e23 Hiphop \u0e44\u0e14\u0e49\u0e44\u0e07\u0e2e\u0e30? A : \u0e40\u0e23\u0e34\u0e48\u0e21\u0e08\u0e32\u0e01\u0e15\u0e2d\u0e19\u0e2d\u0e32\u0e22\u0e38 15 \u0e2d\u0e22\u0e32\u0e01\u0e40\u0e25\u0e48\u0e19 Skateboard \u0e01\u0e47\u0e40\u0e23\u0e34\u0e48\u0e21\u0e44\u0e1b\u0e2b\u0e32\u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32\u0e40\u0e25\u0e48\u0e19 \u0e1d\u0e36\u0e01\u0e40\u0e25\u0e48\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e14\u0e39\u0e15\u0e32\u0e21\u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d \u0e44\u0e21\u0e48\u0e23\u0e39\u0e49\u0e27\u0e48\u0e32\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e17\u0e22\u0e32\u0e04\u0e19\u0e40\u0e04\u0e49\u0e32\u0e40\u0e25\u0e48\u0e19\u0e17\u0e35\u0e48\u0e44\u0e2b\u0e19\u0e01\u0e31\u0e19 \u0e1e\u0e2d\u0e23\u0e39\u0e49\u0e41\u0e25\u0e49\u0e27 \u0e01\u0e47\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e01\u0e25\u0e49\u0e32\u0e44\u0e1b\u0e40\u0e25\u0e48\u0e19\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e49\u0e32 \u0e08\u0e19\u0e27\u0e31\u0e19\u0e19\u0e36\u0e07\u0e01\u0e47\u0e44\u0e14\u0e49\u0e40\u0e08\u0e2d\u0e04\u0e19\u0e43\u0e19\u0e0b\u0e2d\u0e22\u0e1a\u0e49\u0e32\u0e19 \u0e17\u0e35\u0e48\u0e40\u0e25\u0e48\u0e19 Skateboard \u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48\u0e0b\u0e2d\u0e22 6 (\u0e1e\u0e31\u0e17\u0e22\u0e32) \u0e01\u0e47\u0e40\u0e25\u0e22\u0e21\u0e35\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e40\u0e02\u0e49\u0e32\u0e01\u0e25\u0e38\u0e48\u0e21 \u0e04\u0e25\u0e38\u0e01\u0e04\u0e25\u0e35\u0e01\u0e31\u0e1a\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21 Skateboard \u0e01\u0e47\u0e08\u0e30\u0e21\u0e35\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e1f\u0e31\u0e07\u0e40\u0e1e\u0e25\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e19\u0e2d\u0e01\u0e17\u0e38\u0e01\u0e41\u0e19\u0e27 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30 Hardcore \u0e44\u0e1b\u0e22\u0e31\u0e19 Hiphop \u0e41\u0e15\u0e48\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e15\u0e2d\u0e19\u0e19\u0e31\u0e49\u0e19\u0e40\u0e23\u0e32\u0e2d\u0e34\u0e19 \u0e01\u0e31\u0e1a Hiphop [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":321,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false},"categories":[169,179],"tags":[180,181,145],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>THE INTERVIEW : &quot;Ballistic&quot; CEO OF SIAMHIPHOP.COM - RAP IS NOW<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.rapisnow.com\/blog\/the-interview-ballistic-ceo-siamhiphop-com\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"THE INTERVIEW : &quot;Ballistic&quot; CEO OF SIAMHIPHOP.COM - RAP IS NOW\" \/>\n<meta property=\"og:description\" content=\"Ballistic \u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e09\u0e32\u0e22\u0e32 &#8220;\u0e40\u0e08\u0e49\u0e32\u0e1e\u0e48\u0e2d\u0e2a\u0e15\u0e23\u0e35\u0e17\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19&#8221; \u0e08\u0e32\u0e01\u0e41\u0e23\u0e47\u0e1e\u0e40\u0e1b\u0e2d\u0e23\u0e4c \u0e2a\u0e39\u0e48\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e08\u0e4b\u0e07\u0e46 \u0e17\u0e35\u0e48\u0e1c\u0e25\u0e31\u0e01\u0e14\u0e31\u0e19\u0e27\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e15\u0e23\u0e35\u0e17\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e19\u0e27\u0e07\u0e01\u0e32\u0e23\u2028\u0e2e\u0e34\u0e1e\u0e2e\u0e2d\u0e1e \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e22\u0e34\u0e19\u0e14\u0e35\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e40\u0e23\u0e32\u0e44\u0e14\u0e49\u0e21\u0e35\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e21\u0e32\u0e08\u0e31\u0e1a\u0e40\u0e02\u0e48\u0e32\u0e04\u0e38\u0e22\u0e01\u0e31\u0e1a Ballistic \u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e43\u0e19\u0e19\u0e32\u0e21\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 SneakaVilla \u0e40\u0e1b\u0e47\u0e19 DJ \u0e40\u0e1b\u0e47\u0e19\u0e04\u0e19\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19 Event \u0e15\u0e48\u0e32\u0e07\u0e46 &#8230; \u0e42\u0e2d\u0e48&#8230; \u0e17\u0e35\u0e48\u0e40\u0e2d\u0e48\u0e22\u0e21\u0e32\u0e04\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48 &#8220;\u0e41\u0e04\u0e48&#8221; \u0e0b\u0e30\u0e41\u0e25\u0e49\u0e27\u0e25\u0e48\u0e30&#8230; \u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e40\u0e23\u0e32\u0e21\u0e32\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e49\u0e32\u0e41\u0e1a\u0e1a\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e2a\u0e21\u0e31\u0e22\u0e27\u0e31\u0e22\u0e25\u0e30\u0e2d\u0e48\u0e2d\u0e19\u0e01\u0e31\u0e19\u0e14\u0e35\u0e01\u0e27\u0e48\u0e32&#8230; Q : \u0e1a\u0e2d\u0e25\u0e44\u0e14\u0e49\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e27\u0e07\u0e01\u0e32\u0e23 Hiphop \u0e44\u0e14\u0e49\u0e44\u0e07\u0e2e\u0e30? A : \u0e40\u0e23\u0e34\u0e48\u0e21\u0e08\u0e32\u0e01\u0e15\u0e2d\u0e19\u0e2d\u0e32\u0e22\u0e38 15 \u0e2d\u0e22\u0e32\u0e01\u0e40\u0e25\u0e48\u0e19 Skateboard \u0e01\u0e47\u0e40\u0e23\u0e34\u0e48\u0e21\u0e44\u0e1b\u0e2b\u0e32\u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32\u0e40\u0e25\u0e48\u0e19 \u0e1d\u0e36\u0e01\u0e40\u0e25\u0e48\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e14\u0e39\u0e15\u0e32\u0e21\u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d \u0e44\u0e21\u0e48\u0e23\u0e39\u0e49\u0e27\u0e48\u0e32\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e17\u0e22\u0e32\u0e04\u0e19\u0e40\u0e04\u0e49\u0e32\u0e40\u0e25\u0e48\u0e19\u0e17\u0e35\u0e48\u0e44\u0e2b\u0e19\u0e01\u0e31\u0e19 \u0e1e\u0e2d\u0e23\u0e39\u0e49\u0e41\u0e25\u0e49\u0e27 \u0e01\u0e47\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e01\u0e25\u0e49\u0e32\u0e44\u0e1b\u0e40\u0e25\u0e48\u0e19\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e49\u0e32 \u0e08\u0e19\u0e27\u0e31\u0e19\u0e19\u0e36\u0e07\u0e01\u0e47\u0e44\u0e14\u0e49\u0e40\u0e08\u0e2d\u0e04\u0e19\u0e43\u0e19\u0e0b\u0e2d\u0e22\u0e1a\u0e49\u0e32\u0e19 \u0e17\u0e35\u0e48\u0e40\u0e25\u0e48\u0e19 Skateboard \u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48\u0e0b\u0e2d\u0e22 6 (\u0e1e\u0e31\u0e17\u0e22\u0e32) \u0e01\u0e47\u0e40\u0e25\u0e22\u0e21\u0e35\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e40\u0e02\u0e49\u0e32\u0e01\u0e25\u0e38\u0e48\u0e21 \u0e04\u0e25\u0e38\u0e01\u0e04\u0e25\u0e35\u0e01\u0e31\u0e1a\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21 Skateboard \u0e01\u0e47\u0e08\u0e30\u0e21\u0e35\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e1f\u0e31\u0e07\u0e40\u0e1e\u0e25\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e19\u0e2d\u0e01\u0e17\u0e38\u0e01\u0e41\u0e19\u0e27 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30 Hardcore \u0e44\u0e1b\u0e22\u0e31\u0e19 Hiphop \u0e41\u0e15\u0e48\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e15\u0e2d\u0e19\u0e19\u0e31\u0e49\u0e19\u0e40\u0e23\u0e32\u0e2d\u0e34\u0e19 \u0e01\u0e31\u0e1a Hiphop [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.rapisnow.com\/blog\/the-interview-ballistic-ceo-siamhiphop-com\/\" \/>\n<meta property=\"og:site_name\" content=\"RAP IS NOW\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/rapisnow\" \/>\n<meta property=\"article:published_time\" content=\"2015-06-12T06:53:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-10-25T00:44:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball0.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"rapisnow\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.rapisnow.com\/blog\/#website\",\"url\":\"https:\/\/www.rapisnow.com\/blog\/\",\"name\":\"RAP IS NOW\",\"description\":\"Thai Hip-hop Music, Educational and Culture\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.rapisnow.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.rapisnow.com\/blog\/the-interview-ballistic-ceo-siamhiphop-com\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball0.jpg\",\"contentUrl\":\"https:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball0.jpg\",\"width\":640,\"height\":640},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.rapisnow.com\/blog\/the-interview-ballistic-ceo-siamhiphop-com\/#webpage\",\"url\":\"https:\/\/www.rapisnow.com\/blog\/the-interview-ballistic-ceo-siamhiphop-com\/\",\"name\":\"THE INTERVIEW : \\\"Ballistic\\\" CEO OF SIAMHIPHOP.COM - RAP IS NOW\",\"isPartOf\":{\"@id\":\"https:\/\/www.rapisnow.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.rapisnow.com\/blog\/the-interview-ballistic-ceo-siamhiphop-com\/#primaryimage\"},\"datePublished\":\"2015-06-12T06:53:33+00:00\",\"dateModified\":\"2019-10-25T00:44:17+00:00\",\"author\":{\"@id\":\"https:\/\/www.rapisnow.com\/blog\/#\/schema\/person\/a4e1b959906ed00fdfc8a25950b56877\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.rapisnow.com\/blog\/the-interview-ballistic-ceo-siamhiphop-com\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.rapisnow.com\/blog\/the-interview-ballistic-ceo-siamhiphop-com\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.rapisnow.com\/blog\/the-interview-ballistic-ceo-siamhiphop-com\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.rapisnow.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"THE INTERVIEW : &#8220;Ballistic&#8221; CEO OF SIAMHIPHOP.COM\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.rapisnow.com\/blog\/#\/schema\/person\/a4e1b959906ed00fdfc8a25950b56877\",\"name\":\"rapisnow\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.rapisnow.com\/blog\/#personlogo\",\"inLanguage\":\"en-US\",\"url\":\"http:\/\/2.gravatar.com\/avatar\/22cc74eb278702a039021339629d9274?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/2.gravatar.com\/avatar\/22cc74eb278702a039021339629d9274?s=96&d=mm&r=g\",\"caption\":\"rapisnow\"},\"url\":\"https:\/\/www.rapisnow.com\/blog\/author\/rapisnow\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"THE INTERVIEW : \"Ballistic\" CEO OF SIAMHIPHOP.COM - RAP IS NOW","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.rapisnow.com\/blog\/the-interview-ballistic-ceo-siamhiphop-com\/","og_locale":"en_US","og_type":"article","og_title":"THE INTERVIEW : \"Ballistic\" CEO OF SIAMHIPHOP.COM - RAP IS NOW","og_description":"Ballistic \u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e09\u0e32\u0e22\u0e32 &#8220;\u0e40\u0e08\u0e49\u0e32\u0e1e\u0e48\u0e2d\u0e2a\u0e15\u0e23\u0e35\u0e17\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19&#8221; \u0e08\u0e32\u0e01\u0e41\u0e23\u0e47\u0e1e\u0e40\u0e1b\u0e2d\u0e23\u0e4c \u0e2a\u0e39\u0e48\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e40\u0e08\u0e4b\u0e07\u0e46 \u0e17\u0e35\u0e48\u0e1c\u0e25\u0e31\u0e01\u0e14\u0e31\u0e19\u0e27\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e15\u0e23\u0e35\u0e17\u0e41\u0e1f\u0e0a\u0e31\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e19\u0e27\u0e07\u0e01\u0e32\u0e23\u2028\u0e2e\u0e34\u0e1e\u0e2e\u0e2d\u0e1e \u0e40\u0e1b\u0e47\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e19\u0e48\u0e32\u0e22\u0e34\u0e19\u0e14\u0e35\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e40\u0e23\u0e32\u0e44\u0e14\u0e49\u0e21\u0e35\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e21\u0e32\u0e08\u0e31\u0e1a\u0e40\u0e02\u0e48\u0e32\u0e04\u0e38\u0e22\u0e01\u0e31\u0e1a Ballistic \u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19\u0e2d\u0e32\u0e08\u0e08\u0e30\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e43\u0e19\u0e19\u0e32\u0e21\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e41\u0e1a\u0e23\u0e19\u0e14\u0e4c\u0e40\u0e2a\u0e37\u0e49\u0e2d\u0e1c\u0e49\u0e32 SneakaVilla \u0e40\u0e1b\u0e47\u0e19 DJ \u0e40\u0e1b\u0e47\u0e19\u0e04\u0e19\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19 Event \u0e15\u0e48\u0e32\u0e07\u0e46 &#8230; \u0e42\u0e2d\u0e48&#8230; \u0e17\u0e35\u0e48\u0e40\u0e2d\u0e48\u0e22\u0e21\u0e32\u0e04\u0e07\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48 &#8220;\u0e41\u0e04\u0e48&#8221; \u0e0b\u0e30\u0e41\u0e25\u0e49\u0e27\u0e25\u0e48\u0e30&#8230; \u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e40\u0e23\u0e32\u0e21\u0e32\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e49\u0e32\u0e41\u0e1a\u0e1a\u0e15\u0e31\u0e49\u0e07\u0e41\u0e15\u0e48\u0e2a\u0e21\u0e31\u0e22\u0e27\u0e31\u0e22\u0e25\u0e30\u0e2d\u0e48\u0e2d\u0e19\u0e01\u0e31\u0e19\u0e14\u0e35\u0e01\u0e27\u0e48\u0e32&#8230; Q : \u0e1a\u0e2d\u0e25\u0e44\u0e14\u0e49\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e27\u0e07\u0e01\u0e32\u0e23 Hiphop \u0e44\u0e14\u0e49\u0e44\u0e07\u0e2e\u0e30? A : \u0e40\u0e23\u0e34\u0e48\u0e21\u0e08\u0e32\u0e01\u0e15\u0e2d\u0e19\u0e2d\u0e32\u0e22\u0e38 15 \u0e2d\u0e22\u0e32\u0e01\u0e40\u0e25\u0e48\u0e19 Skateboard \u0e01\u0e47\u0e40\u0e23\u0e34\u0e48\u0e21\u0e44\u0e1b\u0e2b\u0e32\u0e0b\u0e37\u0e49\u0e2d\u0e21\u0e32\u0e40\u0e25\u0e48\u0e19 \u0e1d\u0e36\u0e01\u0e40\u0e25\u0e48\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e04\u0e19\u0e40\u0e14\u0e35\u0e22\u0e27\u0e14\u0e39\u0e15\u0e32\u0e21\u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d \u0e44\u0e21\u0e48\u0e23\u0e39\u0e49\u0e27\u0e48\u0e32\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e17\u0e22\u0e32\u0e04\u0e19\u0e40\u0e04\u0e49\u0e32\u0e40\u0e25\u0e48\u0e19\u0e17\u0e35\u0e48\u0e44\u0e2b\u0e19\u0e01\u0e31\u0e19 \u0e1e\u0e2d\u0e23\u0e39\u0e49\u0e41\u0e25\u0e49\u0e27 \u0e01\u0e47\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e01\u0e25\u0e49\u0e32\u0e44\u0e1b\u0e40\u0e25\u0e48\u0e19\u0e01\u0e31\u0e1a\u0e40\u0e04\u0e49\u0e32 \u0e08\u0e19\u0e27\u0e31\u0e19\u0e19\u0e36\u0e07\u0e01\u0e47\u0e44\u0e14\u0e49\u0e40\u0e08\u0e2d\u0e04\u0e19\u0e43\u0e19\u0e0b\u0e2d\u0e22\u0e1a\u0e49\u0e32\u0e19 \u0e17\u0e35\u0e48\u0e40\u0e25\u0e48\u0e19 Skateboard \u0e2d\u0e22\u0e39\u0e48\u0e17\u0e35\u0e48\u0e0b\u0e2d\u0e22 6 (\u0e1e\u0e31\u0e17\u0e22\u0e32) \u0e01\u0e47\u0e40\u0e25\u0e22\u0e21\u0e35\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e40\u0e02\u0e49\u0e32\u0e01\u0e25\u0e38\u0e48\u0e21 \u0e04\u0e25\u0e38\u0e01\u0e04\u0e25\u0e35\u0e01\u0e31\u0e1a\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e01\u0e25\u0e38\u0e48\u0e21 Skateboard \u0e01\u0e47\u0e08\u0e30\u0e21\u0e35\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e1f\u0e31\u0e07\u0e40\u0e1e\u0e25\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e19\u0e2d\u0e01\u0e17\u0e38\u0e01\u0e41\u0e19\u0e27 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30 Hardcore \u0e44\u0e1b\u0e22\u0e31\u0e19 Hiphop \u0e41\u0e15\u0e48\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e2a\u0e36\u0e01\u0e15\u0e2d\u0e19\u0e19\u0e31\u0e49\u0e19\u0e40\u0e23\u0e32\u0e2d\u0e34\u0e19 \u0e01\u0e31\u0e1a Hiphop [&hellip;]","og_url":"https:\/\/www.rapisnow.com\/blog\/the-interview-ballistic-ceo-siamhiphop-com\/","og_site_name":"RAP IS NOW","article_publisher":"https:\/\/www.facebook.com\/rapisnow","article_published_time":"2015-06-12T06:53:33+00:00","article_modified_time":"2019-10-25T00:44:17+00:00","og_image":[{"width":640,"height":640,"url":"https:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball0.jpg","path":"\/home\/rapisnow\/domains\/rapisnow.com\/public_html\/blog\/wp-content\/uploads\/2015\/06\/ball0.jpg","size":"full","id":321,"alt":"","pixels":409600,"type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"rapisnow","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.rapisnow.com\/blog\/#website","url":"https:\/\/www.rapisnow.com\/blog\/","name":"RAP IS NOW","description":"Thai Hip-hop Music, Educational and Culture","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rapisnow.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","@id":"https:\/\/www.rapisnow.com\/blog\/the-interview-ballistic-ceo-siamhiphop-com\/#primaryimage","inLanguage":"en-US","url":"https:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball0.jpg","contentUrl":"https:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball0.jpg","width":640,"height":640},{"@type":"WebPage","@id":"https:\/\/www.rapisnow.com\/blog\/the-interview-ballistic-ceo-siamhiphop-com\/#webpage","url":"https:\/\/www.rapisnow.com\/blog\/the-interview-ballistic-ceo-siamhiphop-com\/","name":"THE INTERVIEW : \"Ballistic\" CEO OF SIAMHIPHOP.COM - RAP IS NOW","isPartOf":{"@id":"https:\/\/www.rapisnow.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.rapisnow.com\/blog\/the-interview-ballistic-ceo-siamhiphop-com\/#primaryimage"},"datePublished":"2015-06-12T06:53:33+00:00","dateModified":"2019-10-25T00:44:17+00:00","author":{"@id":"https:\/\/www.rapisnow.com\/blog\/#\/schema\/person\/a4e1b959906ed00fdfc8a25950b56877"},"breadcrumb":{"@id":"https:\/\/www.rapisnow.com\/blog\/the-interview-ballistic-ceo-siamhiphop-com\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.rapisnow.com\/blog\/the-interview-ballistic-ceo-siamhiphop-com\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.rapisnow.com\/blog\/the-interview-ballistic-ceo-siamhiphop-com\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rapisnow.com\/blog\/"},{"@type":"ListItem","position":2,"name":"THE INTERVIEW : &#8220;Ballistic&#8221; CEO OF SIAMHIPHOP.COM"}]},{"@type":"Person","@id":"https:\/\/www.rapisnow.com\/blog\/#\/schema\/person\/a4e1b959906ed00fdfc8a25950b56877","name":"rapisnow","image":{"@type":"ImageObject","@id":"https:\/\/www.rapisnow.com\/blog\/#personlogo","inLanguage":"en-US","url":"http:\/\/2.gravatar.com\/avatar\/22cc74eb278702a039021339629d9274?s=96&d=mm&r=g","contentUrl":"http:\/\/2.gravatar.com\/avatar\/22cc74eb278702a039021339629d9274?s=96&d=mm&r=g","caption":"rapisnow"},"url":"https:\/\/www.rapisnow.com\/blog\/author\/rapisnow\/"}]}},"jetpack_featured_media_url":"https:\/\/www.rapisnow.com\/blog\/wp-content\/uploads\/2015\/06\/ball0.jpg","jetpack_publicize_connections":[],"jetpack_shortlink":"https:\/\/wp.me\/p64Fqi-59","jetpack_sharing_enabled":true,"jetpack_likes_enabled":true,"_links":{"self":[{"href":"https:\/\/www.rapisnow.com\/blog\/wp-json\/wp\/v2\/posts\/319"}],"collection":[{"href":"https:\/\/www.rapisnow.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.rapisnow.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.rapisnow.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.rapisnow.com\/blog\/wp-json\/wp\/v2\/comments?post=319"}],"version-history":[{"count":8,"href":"https:\/\/www.rapisnow.com\/blog\/wp-json\/wp\/v2\/posts\/319\/revisions"}],"predecessor-version":[{"id":11551,"href":"https:\/\/www.rapisnow.com\/blog\/wp-json\/wp\/v2\/posts\/319\/revisions\/11551"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.rapisnow.com\/blog\/wp-json\/wp\/v2\/media\/321"}],"wp:attachment":[{"href":"https:\/\/www.rapisnow.com\/blog\/wp-json\/wp\/v2\/media?parent=319"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.rapisnow.com\/blog\/wp-json\/wp\/v2\/categories?post=319"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.rapisnow.com\/blog\/wp-json\/wp\/v2\/tags?post=319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}